{"id":17,"count":3,"description":"","link":"https:\/\/neurontechlabs.com\/index.php\/category\/latest-news-v2\/","name":"Latest News V2","slug":"latest-news-v2","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/neurontechlabs.com\/index.php\/wp-json\/wp\/v2\/categories\/17"}],"collection":[{"href":"https:\/\/neurontechlabs.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/neurontechlabs.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/neurontechlabs.com\/index.php\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}